{"id":47,"date":"2019-08-28T12:45:13","date_gmt":"2019-08-28T12:45:13","guid":{"rendered":"http:\/\/wordpress.ft.unicamp.br\/procedimentos\/?p=47"},"modified":"2021-03-10T13:23:34","modified_gmt":"2021-03-10T13:23:34","slug":"cadastro-de-alunos-do-cotil","status":"publish","type":"post","link":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/cadastro-de-alunos-do-cotil\/","title":{"rendered":"Cadastro de Alunos do Cotil"},"content":{"rendered":"\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Nome do procedimento<\/td><td>Cadastro de Alunos do Col\u00e9gio T\u00e9cnico de Limeira<\/td><\/tr><tr><td>Objetivo<\/td><td>Cadastrar alunos do Col\u00e9gio T\u00e9cnico de Limeira<\/td><\/tr><tr><td>A quem se destina<\/td><td>Alunos do Col\u00e9gio T\u00e9cnico de Limeira<\/td><\/tr><tr><td>Hor\u00e1rio de atendimento<\/td><td>08h00 \u00e0s 22h30, de segunda a sexta-feira<\/td><\/tr><tr><td>Formato de Pedido\/Entrega<\/td><td>Para que o aluno possa ser cadastrado na biblioteca, um cadastro pr\u00e9vio dos alunos \u00e9 feito em lote, pela empresa Prima, que administra o Software Sophia. Solicita-se uma lista ao setor de Inform\u00e1tica do Cotil, com os dados principais: Nome, R.A., curso, endere\u00e7o completo, telefone e e-mail. Essa lista \u00e9 enviada ao Grupo Gestor do Sophia, que passa para a empresa Prima.<\/td><\/tr><tr><td>Funcion\u00e1rio Respons\u00e1vel<\/td><td>&nbsp;<\/td><\/tr><tr><td>Protocolo entregue ao requerente<\/td><td>&nbsp;<\/td><\/tr><tr><td>Formul\u00e1rios exigidos<\/td><td>Na primeira visita do aluno \u00e0 Biblioteca, dados pessoais ser\u00e3o conferidos pelo operador.<\/td><\/tr><tr><td>Tempo de espera<\/td><td>Imediato<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Nome do procedimento Cadastro de Alunos do Col\u00e9gio T\u00e9cnico de Limeira Objetivo Cadastrar alunos do Col\u00e9gio T\u00e9cnico de Limeira A quem se destina Alunos do Col\u00e9gio T\u00e9cnico de\u2026<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-47","post","type-post","status-publish","format-standard","hentry","category-biblioteca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cadastro de Alunos do Cotil - Procedimentos da FT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/cadastro-de-alunos-do-cotil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cadastro de Alunos do Cotil - Procedimentos da FT\" \/>\n<meta property=\"og:description\" content=\"Nome do procedimento Cadastro de Alunos do Col\u00e9gio T\u00e9cnico de Limeira Objetivo Cadastrar alunos do Col\u00e9gio T\u00e9cnico de Limeira A quem se destina Alunos do Col\u00e9gio T\u00e9cnico de\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/cadastro-de-alunos-do-cotil\/\" \/>\n<meta property=\"og:site_name\" content=\"Procedimentos da FT\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-28T12:45:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-10T13:23:34+00:00\" \/>\n<meta name=\"author\" content=\"root\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"root\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/cadastro-de-alunos-do-cotil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/cadastro-de-alunos-do-cotil\\\/\"},\"author\":{\"name\":\"root\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/#\\\/schema\\\/person\\\/e2911a1cf8df1dab82f1b39d1e8a0174\"},\"headline\":\"Cadastro de Alunos do Cotil\",\"datePublished\":\"2019-08-28T12:45:13+00:00\",\"dateModified\":\"2021-03-10T13:23:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/cadastro-de-alunos-do-cotil\\\/\"},\"wordCount\":149,\"articleSection\":[\"Biblioteca\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/cadastro-de-alunos-do-cotil\\\/\",\"url\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/cadastro-de-alunos-do-cotil\\\/\",\"name\":\"Cadastro de Alunos do Cotil - Procedimentos da FT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/#website\"},\"datePublished\":\"2019-08-28T12:45:13+00:00\",\"dateModified\":\"2021-03-10T13:23:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/#\\\/schema\\\/person\\\/e2911a1cf8df1dab82f1b39d1e8a0174\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/cadastro-de-alunos-do-cotil\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/cadastro-de-alunos-do-cotil\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/cadastro-de-alunos-do-cotil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cadastro de Alunos do Cotil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/#website\",\"url\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/\",\"name\":\"Procedimentos da FT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/#\\\/schema\\\/person\\\/e2911a1cf8df1dab82f1b39d1e8a0174\",\"name\":\"root\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cecc207f725314e58327a0cc44d2cbeb3edabcaee67284b5747c28f58c76a3e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cecc207f725314e58327a0cc44d2cbeb3edabcaee67284b5747c28f58c76a3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cecc207f725314e58327a0cc44d2cbeb3edabcaee67284b5747c28f58c76a3e?s=96&d=mm&r=g\",\"caption\":\"root\"},\"url\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/author\\\/root\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cadastro de Alunos do Cotil - Procedimentos da FT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/cadastro-de-alunos-do-cotil\/","og_locale":"pt_BR","og_type":"article","og_title":"Cadastro de Alunos do Cotil - Procedimentos da FT","og_description":"Nome do procedimento Cadastro de Alunos do Col\u00e9gio T\u00e9cnico de Limeira Objetivo Cadastrar alunos do Col\u00e9gio T\u00e9cnico de Limeira A quem se destina Alunos do Col\u00e9gio T\u00e9cnico de\u2026","og_url":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/cadastro-de-alunos-do-cotil\/","og_site_name":"Procedimentos da FT","article_published_time":"2019-08-28T12:45:13+00:00","article_modified_time":"2021-03-10T13:23:34+00:00","author":"root","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"root","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/cadastro-de-alunos-do-cotil\/#article","isPartOf":{"@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/cadastro-de-alunos-do-cotil\/"},"author":{"name":"root","@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/#\/schema\/person\/e2911a1cf8df1dab82f1b39d1e8a0174"},"headline":"Cadastro de Alunos do Cotil","datePublished":"2019-08-28T12:45:13+00:00","dateModified":"2021-03-10T13:23:34+00:00","mainEntityOfPage":{"@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/cadastro-de-alunos-do-cotil\/"},"wordCount":149,"articleSection":["Biblioteca"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/cadastro-de-alunos-do-cotil\/","url":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/cadastro-de-alunos-do-cotil\/","name":"Cadastro de Alunos do Cotil - Procedimentos da FT","isPartOf":{"@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/#website"},"datePublished":"2019-08-28T12:45:13+00:00","dateModified":"2021-03-10T13:23:34+00:00","author":{"@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/#\/schema\/person\/e2911a1cf8df1dab82f1b39d1e8a0174"},"breadcrumb":{"@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/cadastro-de-alunos-do-cotil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wordpress.ft.unicamp.br\/procedimentos\/cadastro-de-alunos-do-cotil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/cadastro-de-alunos-do-cotil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/"},{"@type":"ListItem","position":2,"name":"Cadastro de Alunos do Cotil"}]},{"@type":"WebSite","@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/#website","url":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/","name":"Procedimentos da FT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/#\/schema\/person\/e2911a1cf8df1dab82f1b39d1e8a0174","name":"root","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/6cecc207f725314e58327a0cc44d2cbeb3edabcaee67284b5747c28f58c76a3e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6cecc207f725314e58327a0cc44d2cbeb3edabcaee67284b5747c28f58c76a3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6cecc207f725314e58327a0cc44d2cbeb3edabcaee67284b5747c28f58c76a3e?s=96&d=mm&r=g","caption":"root"},"url":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/author\/root\/"}]}},"_links":{"self":[{"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/posts\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":2,"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/posts\/47\/revisions"}],"predecessor-version":[{"id":383,"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/posts\/47\/revisions\/383"}],"wp:attachment":[{"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/media?parent=47"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/categories?post=47"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/tags?post=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}