{"id":73,"date":"2019-08-28T12:58:16","date_gmt":"2019-08-28T12:58:16","guid":{"rendered":"http:\/\/wordpress.ft.unicamp.br\/procedimentos\/?p=73"},"modified":"2019-08-28T12:58:17","modified_gmt":"2019-08-28T12:58:17","slug":"reservas","status":"publish","type":"post","link":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/reservas\/","title":{"rendered":"Reservas"},"content":{"rendered":"\n<table class=\"wp-block-table\"><tbody><tr><td>Nome do procedimento<\/td><td>Reservas<\/td><\/tr><tr><td>Objetivo<\/td><td>Quando um t\u00edtulo estiver emprestado e n\u00e3o houver mais exemplares dispon\u00edveis, o usu\u00e1rio pode fazer a reserva do mesmo, de forma que o(s) exemplar(es) fique(m) retido(s) e separado(s) quando for devolvido.<\/td><\/tr><tr><td>A quem se destina<\/td><td>Usu\u00e1rios cadastrados na biblioteca<\/td><\/tr><tr><td>Hor\u00e1rio de atendimento<\/td><td>Online<\/td><\/tr><tr><td>Formato de Pedido\/Entrega<\/td><td>A reserva segue a fila em ordem cronol\u00f3gica e s\u00f3 pode ser feita pelo usu\u00e1rio, pela internet, acessando o site acervus.unicamp.br ou pelo aplicativo SophiA Biblioteca. Devem ser utilizados e-mail (no campo de login) e senha da Biblioteca.<\/td><\/tr><tr><td>Funcion\u00e1rio Respons\u00e1vel<\/td><td>Online<\/td><\/tr><tr><td>Protocolo entregue ao requerente<\/td><td>&nbsp;<\/td><\/tr><tr><td>Formul\u00e1rios exigidos<\/td><td>&nbsp;<\/td><\/tr><tr><td>Tempo de espera<\/td><td>As libera\u00e7\u00f5es v\u00e3o ocorrendo conforme os exemplares s\u00e3o devolvidos. O usu\u00e1rio que fez a reserva \u00e9 notificado por e-mail e tem at\u00e9 o fim do expediente do dia \u00fatil seguinte para retirar, caso contr\u00e1rio a reserva vai para o pr\u00f3ximo da lista ou o exemplar fica dispon\u00edvel e volta ao acervo.<\/td><\/tr><tr><td>Procedimento relacionado<\/td><td>&nbsp;<\/td><\/tr><tr><td>Outros<\/td><td>Somente o usu\u00e1rio poder\u00e1 fazer o cancelamento de uma reserva acessando sua \u00e1rea de reservas ativas no site ou aplicativos citados acima.<\/td><\/tr><\/tbody><\/table>\n","protected":false},"excerpt":{"rendered":"<p>Nome do procedimento Reservas Objetivo Quando um t\u00edtulo estiver emprestado e n\u00e3o houver mais exemplares dispon\u00edveis, o usu\u00e1rio pode fazer a reserva do mesmo, de forma que o(s)\u2026<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-73","post","type-post","status-publish","format-standard","hentry","category-biblioteca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reservas - Procedimentos da FT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/reservas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reservas - Procedimentos da FT\" \/>\n<meta property=\"og:description\" content=\"Nome do procedimento Reservas Objetivo Quando um t\u00edtulo estiver emprestado e n\u00e3o houver mais exemplares dispon\u00edveis, o usu\u00e1rio pode fazer a reserva do mesmo, de forma que o(s)\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/reservas\/\" \/>\n<meta property=\"og:site_name\" content=\"Procedimentos da FT\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-28T12:58:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-28T12:58:17+00:00\" \/>\n<meta name=\"author\" content=\"root\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"root\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/reservas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/reservas\\\/\"},\"author\":{\"name\":\"root\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/#\\\/schema\\\/person\\\/e2911a1cf8df1dab82f1b39d1e8a0174\"},\"headline\":\"Reservas\",\"datePublished\":\"2019-08-28T12:58:16+00:00\",\"dateModified\":\"2019-08-28T12:58:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/reservas\\\/\"},\"wordCount\":207,\"articleSection\":[\"Biblioteca\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/reservas\\\/\",\"url\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/reservas\\\/\",\"name\":\"Reservas - Procedimentos da FT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/#website\"},\"datePublished\":\"2019-08-28T12:58:16+00:00\",\"dateModified\":\"2019-08-28T12:58:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/#\\\/schema\\\/person\\\/e2911a1cf8df1dab82f1b39d1e8a0174\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/reservas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/reservas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/reservas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reservas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/#website\",\"url\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/\",\"name\":\"Procedimentos da FT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/#\\\/schema\\\/person\\\/e2911a1cf8df1dab82f1b39d1e8a0174\",\"name\":\"root\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cecc207f725314e58327a0cc44d2cbeb3edabcaee67284b5747c28f58c76a3e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cecc207f725314e58327a0cc44d2cbeb3edabcaee67284b5747c28f58c76a3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cecc207f725314e58327a0cc44d2cbeb3edabcaee67284b5747c28f58c76a3e?s=96&d=mm&r=g\",\"caption\":\"root\"},\"url\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/procedimentos\\\/author\\\/root\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reservas - Procedimentos da FT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/reservas\/","og_locale":"pt_BR","og_type":"article","og_title":"Reservas - Procedimentos da FT","og_description":"Nome do procedimento Reservas Objetivo Quando um t\u00edtulo estiver emprestado e n\u00e3o houver mais exemplares dispon\u00edveis, o usu\u00e1rio pode fazer a reserva do mesmo, de forma que o(s)\u2026","og_url":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/reservas\/","og_site_name":"Procedimentos da FT","article_published_time":"2019-08-28T12:58:16+00:00","article_modified_time":"2019-08-28T12:58:17+00:00","author":"root","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"root","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/reservas\/#article","isPartOf":{"@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/reservas\/"},"author":{"name":"root","@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/#\/schema\/person\/e2911a1cf8df1dab82f1b39d1e8a0174"},"headline":"Reservas","datePublished":"2019-08-28T12:58:16+00:00","dateModified":"2019-08-28T12:58:17+00:00","mainEntityOfPage":{"@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/reservas\/"},"wordCount":207,"articleSection":["Biblioteca"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/reservas\/","url":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/reservas\/","name":"Reservas - Procedimentos da FT","isPartOf":{"@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/#website"},"datePublished":"2019-08-28T12:58:16+00:00","dateModified":"2019-08-28T12:58:17+00:00","author":{"@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/#\/schema\/person\/e2911a1cf8df1dab82f1b39d1e8a0174"},"breadcrumb":{"@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/reservas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wordpress.ft.unicamp.br\/procedimentos\/reservas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/reservas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/"},{"@type":"ListItem","position":2,"name":"Reservas"}]},{"@type":"WebSite","@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/#website","url":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/","name":"Procedimentos da FT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/#\/schema\/person\/e2911a1cf8df1dab82f1b39d1e8a0174","name":"root","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/6cecc207f725314e58327a0cc44d2cbeb3edabcaee67284b5747c28f58c76a3e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6cecc207f725314e58327a0cc44d2cbeb3edabcaee67284b5747c28f58c76a3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6cecc207f725314e58327a0cc44d2cbeb3edabcaee67284b5747c28f58c76a3e?s=96&d=mm&r=g","caption":"root"},"url":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/author\/root\/"}]}},"_links":{"self":[{"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/posts\/73","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/comments?post=73"}],"version-history":[{"count":1,"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/posts\/73\/revisions"}],"predecessor-version":[{"id":74,"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/posts\/73\/revisions\/74"}],"wp:attachment":[{"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/media?parent=73"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/categories?post=73"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.ft.unicamp.br\/procedimentos\/wp-json\/wp\/v2\/tags?post=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}