{"id":80,"date":"2014-09-21T22:53:58","date_gmt":"2014-09-21T22:53:58","guid":{"rendered":"http:\/\/www.ft.unicamp.br\/rodrigos\/?p=80"},"modified":"2017-03-28T15:45:04","modified_gmt":"2017-03-28T15:45:04","slug":"chegando-a-waterford","status":"publish","type":"post","link":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/","title":{"rendered":"Chegando a Waterford"},"content":{"rendered":"<div id=\"attachment_86\" style=\"width: 178px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_113930983.jpg\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-86\" class=\"wp-image-86 size-medium\" src=\"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_113930983-168x300.jpg\" alt=\"\" width=\"168\" height=\"300\" \/><\/a><p id=\"caption-attachment-86\" class=\"wp-caption-text\">Centro da cidade de Waterford.<\/p><\/div>\n<div id=\"attachment_84\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_120126660.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-84\" class=\"wp-image-84\" src=\"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_120126660-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" \/><\/a><p id=\"caption-attachment-84\" class=\"wp-caption-text\">T\u00edpicas casas da cidade.<\/p><\/div>\n<div id=\"attachment_83\" style=\"width: 178px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_122515265.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-83\" class=\"wp-image-83 size-medium\" src=\"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_122515265-168x300.jpg\" alt=\"\" width=\"168\" height=\"300\" \/><\/a><p id=\"caption-attachment-83\" class=\"wp-caption-text\">Caf\u00e9 t\u00edpico no centro.<\/p><\/div>\n<div id=\"attachment_82\" style=\"width: 178px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_122757615.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-82\" class=\"wp-image-82 size-medium\" src=\"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_122757615-168x300.jpg\" alt=\"\" width=\"168\" height=\"300\" \/><\/a><p id=\"caption-attachment-82\" class=\"wp-caption-text\">Centro da cidade.<\/p><\/div>\n<div id=\"attachment_81\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_131159942.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-81\" class=\"wp-image-81 size-medium\" src=\"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_131159942-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" \/><\/a><p id=\"caption-attachment-81\" class=\"wp-caption-text\">Vista da ba\u00eda do porto de Waterford.<\/p><\/div>\n<p>Hoje cheguei a cidade de Waterford. Cidade que foi fundada por vinkings no ano de 914 (completou recentemente 1100 anos) e atualmente \u00e9 a 5a. maior cidade da Irlanda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje cheguei a cidade de Waterford. Cidade que foi fundada por vinkings no ano de 914 (completou recentemente 1100 anos) e atualmente \u00e9 a 5a. maior cidade da Irlanda.<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-80","post","type-post","status-publish","format-standard","hentry","category-aspectos-urbanos-e-culturais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chegando a Waterford - Interc\u00e2mbio no Instituto de Tecnologia de Waterford<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chegando a Waterford - Interc\u00e2mbio no Instituto de Tecnologia de Waterford\" \/>\n<meta property=\"og:description\" content=\"Hoje cheguei a cidade de Waterford. Cidade que foi fundada por vinkings no ano de 914 (completou recentemente 1100 anos) e atualmente \u00e9 a 5a. maior cidade da Irlanda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/\" \/>\n<meta property=\"og:site_name\" content=\"Interc\u00e2mbio no Instituto de Tecnologia de Waterford\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-21T22:53:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-03-28T15:45:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_113930983-168x300.jpg\" \/>\n<meta name=\"author\" content=\"Rodrigo Gon\u00e7alves Silvestre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rodrigo Gon\u00e7alves Silvestre\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/chegando-a-waterford\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/chegando-a-waterford\\\/\"},\"author\":{\"name\":\"Rodrigo Gon\u00e7alves Silvestre\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/#\\\/schema\\\/person\\\/878f8845565e95ba5316fe50db1c3810\"},\"headline\":\"Chegando a Waterford\",\"datePublished\":\"2014-09-21T22:53:58+00:00\",\"dateModified\":\"2017-03-28T15:45:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/chegando-a-waterford\\\/\"},\"wordCount\":90,\"image\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/chegando-a-waterford\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2014\\\/09\\\/IMG_20140921_113930983-168x300.jpg\",\"articleSection\":[\"Aspectos Urbanos e Culturais\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/chegando-a-waterford\\\/\",\"url\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/chegando-a-waterford\\\/\",\"name\":\"Chegando a Waterford - Interc\u00e2mbio no Instituto de Tecnologia de Waterford\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/chegando-a-waterford\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/chegando-a-waterford\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2014\\\/09\\\/IMG_20140921_113930983-168x300.jpg\",\"datePublished\":\"2014-09-21T22:53:58+00:00\",\"dateModified\":\"2017-03-28T15:45:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/#\\\/schema\\\/person\\\/878f8845565e95ba5316fe50db1c3810\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/chegando-a-waterford\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/chegando-a-waterford\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/chegando-a-waterford\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2014\\\/09\\\/IMG_20140921_113930983.jpg\",\"contentUrl\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2014\\\/09\\\/IMG_20140921_113930983.jpg\",\"width\":1456,\"height\":2592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/chegando-a-waterford\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chegando a Waterford\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/#website\",\"url\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/\",\"name\":\"Interc\u00e2mbio no Instituto de Tecnologia de Waterford\",\"description\":\"Participa\u00e7\u00e3o no programa de mobilidade de funcion\u00e1rios da UNICAMP na Irlanda no per\u00edodo de 19\\\/09 a 06\\\/10 de 2014.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/#\\\/schema\\\/person\\\/878f8845565e95ba5316fe50db1c3810\",\"name\":\"Rodrigo Gon\u00e7alves Silvestre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4054d9c9591c4df4e982441bda81f2856683c8fc0d45ee5eaa224c4b2bd52bd8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4054d9c9591c4df4e982441bda81f2856683c8fc0d45ee5eaa224c4b2bd52bd8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4054d9c9591c4df4e982441bda81f2856683c8fc0d45ee5eaa224c4b2bd52bd8?s=96&d=mm&r=g\",\"caption\":\"Rodrigo Gon\u00e7alves Silvestre\"},\"url\":\"https:\\\/\\\/wordpress.ft.unicamp.br\\\/rodrigos\\\/author\\\/rodrigo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chegando a Waterford - Interc\u00e2mbio no Instituto de Tecnologia de Waterford","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/","og_locale":"pt_BR","og_type":"article","og_title":"Chegando a Waterford - Interc\u00e2mbio no Instituto de Tecnologia de Waterford","og_description":"Hoje cheguei a cidade de Waterford. Cidade que foi fundada por vinkings no ano de 914 (completou recentemente 1100 anos) e atualmente \u00e9 a 5a. maior cidade da Irlanda.","og_url":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/","og_site_name":"Interc\u00e2mbio no Instituto de Tecnologia de Waterford","article_published_time":"2014-09-21T22:53:58+00:00","article_modified_time":"2017-03-28T15:45:04+00:00","og_image":[{"url":"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_113930983-168x300.jpg","type":"","width":"","height":""}],"author":"Rodrigo Gon\u00e7alves Silvestre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rodrigo Gon\u00e7alves Silvestre"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/#article","isPartOf":{"@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/"},"author":{"name":"Rodrigo Gon\u00e7alves Silvestre","@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/#\/schema\/person\/878f8845565e95ba5316fe50db1c3810"},"headline":"Chegando a Waterford","datePublished":"2014-09-21T22:53:58+00:00","dateModified":"2017-03-28T15:45:04+00:00","mainEntityOfPage":{"@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/"},"wordCount":90,"image":{"@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/#primaryimage"},"thumbnailUrl":"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_113930983-168x300.jpg","articleSection":["Aspectos Urbanos e Culturais"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/","url":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/","name":"Chegando a Waterford - Interc\u00e2mbio no Instituto de Tecnologia de Waterford","isPartOf":{"@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/#primaryimage"},"image":{"@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/#primaryimage"},"thumbnailUrl":"http:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_113930983-168x300.jpg","datePublished":"2014-09-21T22:53:58+00:00","dateModified":"2017-03-28T15:45:04+00:00","author":{"@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/#\/schema\/person\/878f8845565e95ba5316fe50db1c3810"},"breadcrumb":{"@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/#primaryimage","url":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_113930983.jpg","contentUrl":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-content\/uploads\/sites\/17\/2014\/09\/IMG_20140921_113930983.jpg","width":1456,"height":2592},{"@type":"BreadcrumbList","@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/chegando-a-waterford\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/"},{"@type":"ListItem","position":2,"name":"Chegando a Waterford"}]},{"@type":"WebSite","@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/#website","url":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/","name":"Interc\u00e2mbio no Instituto de Tecnologia de Waterford","description":"Participa\u00e7\u00e3o no programa de mobilidade de funcion\u00e1rios da UNICAMP na Irlanda no per\u00edodo de 19\/09 a 06\/10 de 2014.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/#\/schema\/person\/878f8845565e95ba5316fe50db1c3810","name":"Rodrigo Gon\u00e7alves Silvestre","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/4054d9c9591c4df4e982441bda81f2856683c8fc0d45ee5eaa224c4b2bd52bd8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4054d9c9591c4df4e982441bda81f2856683c8fc0d45ee5eaa224c4b2bd52bd8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4054d9c9591c4df4e982441bda81f2856683c8fc0d45ee5eaa224c4b2bd52bd8?s=96&d=mm&r=g","caption":"Rodrigo Gon\u00e7alves Silvestre"},"url":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/author\/rodrigo\/"}]}},"_links":{"self":[{"href":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-json\/wp\/v2\/posts\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":1,"href":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-json\/wp\/v2\/posts\/80\/revisions"}],"predecessor-version":[{"id":220,"href":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-json\/wp\/v2\/posts\/80\/revisions\/220"}],"wp:attachment":[{"href":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-json\/wp\/v2\/media?parent=80"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-json\/wp\/v2\/categories?post=80"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.ft.unicamp.br\/rodrigos\/wp-json\/wp\/v2\/tags?post=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}